{"id":1127,"date":"2018-02-05T09:27:04","date_gmt":"2018-02-05T09:27:04","guid":{"rendered":"http:\/\/www.mangelsmestre.com\/main\/?p=1127"},"modified":"2018-02-05T09:27:04","modified_gmt":"2018-02-05T09:27:04","slug":"como-preparar-kimpira","status":"publish","type":"post","link":"https:\/\/www.mangelsmestre.com\/main\/como-preparar-kimpira\/","title":{"rendered":"\u00bfC\u00f3mo preparar Kimpira?"},"content":{"rendered":"<h4><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter  wp-image-1129\" src=\"http:\/\/www.mangelsmestre.com\/main\/wp-content\/uploads\/2018\/02\/Kimpira_03.jpg\" alt=\"\" width=\"654\" height=\"436\" \/><\/h4>\n<h4><strong>\u00bfQu\u00e9 es la Kimpira?<\/strong><\/h4>\n<p><strong>Kimpira<\/strong> es un estilo de cocci\u00f3n de verduras de ra\u00edz que consiste en un salteado largo con aceite de s\u00e9samo, muy poca agua y, al finalizar, se les a\u00f1ade un poquito de salsa tamari.<\/p>\n<p>Durante el invierno las ra\u00edces acumulan la mayor\u00eda de nutrientes.<\/p>\n<p>La ra\u00edz de <strong>bardana<\/strong> (r\u00e1bano negro) es muy yang, depurativa de la sangre, revitalizante y adecuada para el reuma. Se usa como antibi\u00f3tico natural.<\/p>\n<p>La <strong>zanahoria<\/strong>\u00a0\u00a0es rica en fibra , \u00e1cido f\u00f3lico, potasio, calcio, magnesio y antioxidantes, adem\u00e1s contiene betacarotenos, que nuestro organismo transforma en vitamina A. Su contenido en vitamina C, especialmente en las hojas, es mucho m\u00e1s elevado que el de las naranjas. Es una ra\u00edz muy adecuada para todas las patolog\u00edas digestivas. Pelada y hervida, como alimento diario, es ideal para la celiaqu\u00eda. Adem\u00e1s, por su porcentaje en fitoqu\u00edmicos es anticancer\u00edgena.\u00a0 Este alimento contribuye a mantener nuestra vista, aumenta las defensas, disminuye el colesterol y previene la arteriosclerosis.<\/p>\n<p>&nbsp;<\/p>\n<h4><strong>Ingredientes para preparar Kimpira<\/strong><\/h4>\n<ul>\n<li>2 ra\u00edces de bardana peladas y cortadas oblicuas y finas (1mm de grosor)<\/li>\n<li>2 zanahorias cortadas del mismo modo que la bardana<\/li>\n<li>1 cucharada sopera de aceite de s\u00e9samo<\/li>\n<li>1 cucharada sopera de jengibre rallado<\/li>\n<li>1 cucharada sopera de tamari<\/li>\n<li>Sal marina<\/li>\n<li>Agua\n<p><figure id=\"attachment_1130\" aria-describedby=\"caption-attachment-1130\" style=\"width: 450px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-1130 size-full\" src=\"http:\/\/www.mangelsmestre.com\/main\/wp-content\/uploads\/2018\/02\/Kimpira_04.jpg\" alt=\"\" width=\"450\" height=\"300\" \/><figcaption id=\"caption-attachment-1130\" class=\"wp-caption-text\">Ra\u00edz de bardana<\/figcaption><\/figure><\/li>\n<\/ul>\n<h4><strong>Preparaci\u00f3n:<\/strong><\/h4>\n<ol>\n<li>Poner la cazuela al fuego. Verter el aceite y cuando est\u00e9 caliente echar primero la bardana para saltearla. Despu\u00e9s bajar el fuego y a\u00f1adir una pizca de sal.<\/li>\n<li>Cuando la bardana est\u00e9 medio tierna, se a\u00f1ade la zanahoria y un poquito de agua para que no se quemen. A continuaci\u00f3n tapamos.<\/li>\n<li>Se deja cocer a fuego lento durante 10 minutos. Si ya est\u00e1n bien cocidas se apaga el fuego y se a\u00f1ade el jengibre y el tamari.<\/li>\n<\/ol>\n<p>&nbsp;<\/p>\n<p>Aprende m\u00e1s recetas en <a href=\"http:\/\/www.mangelsmestre.com\/main\/adquirir-libros\/\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Recetas Macrobi\u00f3ticas para la Salud<\/strong><\/a>.\t\t<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00bfQu\u00e9 es la Kimpira? Kimpira es un estilo de cocci\u00f3n de verduras de ra\u00edz que consiste en un salteado largo [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1129,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[35,44,64,71,97,98,102],"class_list":["post-1127","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categoria","tag-alimentacion","tag-cancer","tag-enfermedades-y-alimentacion","tag-fibromialgia","tag-recetas","tag-recetas-macrobioticas-para-la-salud","tag-sindrome-de-fatiga-cronica"],"_links":{"self":[{"href":"https:\/\/www.mangelsmestre.com\/main\/wp-json\/wp\/v2\/posts\/1127","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mangelsmestre.com\/main\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.mangelsmestre.com\/main\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.mangelsmestre.com\/main\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mangelsmestre.com\/main\/wp-json\/wp\/v2\/comments?post=1127"}],"version-history":[{"count":0,"href":"https:\/\/www.mangelsmestre.com\/main\/wp-json\/wp\/v2\/posts\/1127\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.mangelsmestre.com\/main\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/www.mangelsmestre.com\/main\/wp-json\/wp\/v2\/media?parent=1127"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.mangelsmestre.com\/main\/wp-json\/wp\/v2\/categories?post=1127"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.mangelsmestre.com\/main\/wp-json\/wp\/v2\/tags?post=1127"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}