{"id":1272,"date":"2018-12-13T08:48:22","date_gmt":"2018-12-13T08:48:22","guid":{"rendered":"http:\/\/www.mangelsmestre.com\/main\/?p=1272"},"modified":"2019-06-17T20:00:46","modified_gmt":"2019-06-17T18:00:46","slug":"nuevo-libro-despierta-busca-la-verdad","status":"publish","type":"post","link":"https:\/\/www.mangelsmestre.com\/main\/nuevo-libro-despierta-busca-la-verdad\/","title":{"rendered":"Nuevo libro: Despierta!!! Busca la Verdad"},"content":{"rendered":"<p>\t\t\t\tCon motivo de mi aniversario el domingo 11 del 11 del 11 publiqu\u00e9 mi nuevo libro <a href=\"http:\/\/www.mangelsmestre.com\/descargas\/despierta.pdf\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Despierta!!! Busca la Verdad<\/strong><\/a>.\u00a0 Este libro\u00a0 quiere alejarse\u00a0de todas las estructuras del sistema actual en todos sus aspectos, en lo pol\u00edtico, social, econ\u00f3mico y religioso.<\/p>\n<p><a href=\"http:\/\/www.mangelsmestre.com\/main\/libros-gratuitos\/\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-1273 alignleft\" src=\"http:\/\/www.mangelsmestre.com\/main\/wp-content\/uploads\/2018\/11\/Portada-Definitiva-llibre-6.png\" alt=\"\" width=\"432\" height=\"648\" \/><\/a><\/p>\n<p>A lo largo de los 16 cap\u00edtulos que componen el libro\u00a0 quiero mostrar\u00a0una nueva humanidad con conciencia cr\u00edstica, que viva en paz sin conflictos, con solidaridad para llegar a Dios sin depender de ninguna instituci\u00f3n.<\/p>\n<p>Este libro est\u00e1 dirigido sobre todo a las personas que se cuestionan, tienen inquietudes y no se conforman con lo establecido.<\/p>\n<p>La finalidad de la obra es despertar conciencia mediante el conocimiento de la verdad.<\/p>\n<p>\u00a1Deseo que os guste y que os sorprenda!<\/p>\n<p>&nbsp;<\/p>\n<h4><strong>Descarga el libro gratuito en formato digital desde mi <a href=\"http:\/\/www.mangelsmestre.com\/descargas\/despierta.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">p\u00e1gina web<\/a>.<\/strong><\/h4>\n<h4><strong>\u00a0<\/strong><\/h4>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><strong>El libro en papel se publicar\u00e1 en las pr\u00f3ximas semanas.<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;\t\t<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con motivo de mi aniversario el domingo 11 del 11 del 11 publiqu\u00e9 mi nuevo libro Despierta!!! Busca la Verdad.\u00a0 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1894,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[41,42,50,78,85],"class_list":["post-1272","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categoria","tag-autoayuda","tag-autoconocimiento","tag-crecimiento-espiritual","tag-historia","tag-libros"],"_links":{"self":[{"href":"https:\/\/www.mangelsmestre.com\/main\/wp-json\/wp\/v2\/posts\/1272","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mangelsmestre.com\/main\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.mangelsmestre.com\/main\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.mangelsmestre.com\/main\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mangelsmestre.com\/main\/wp-json\/wp\/v2\/comments?post=1272"}],"version-history":[{"count":1,"href":"https:\/\/www.mangelsmestre.com\/main\/wp-json\/wp\/v2\/posts\/1272\/revisions"}],"predecessor-version":[{"id":1895,"href":"https:\/\/www.mangelsmestre.com\/main\/wp-json\/wp\/v2\/posts\/1272\/revisions\/1895"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.mangelsmestre.com\/main\/wp-json\/wp\/v2\/media\/1894"}],"wp:attachment":[{"href":"https:\/\/www.mangelsmestre.com\/main\/wp-json\/wp\/v2\/media?parent=1272"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.mangelsmestre.com\/main\/wp-json\/wp\/v2\/categories?post=1272"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.mangelsmestre.com\/main\/wp-json\/wp\/v2\/tags?post=1272"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}